{"id":31679,"date":"2021-05-10T06:58:58","date_gmt":"2021-05-10T06:58:58","guid":{"rendered":"https:\/\/www.keyter.com\/la-incomprendida-calculadora-de-harvard\/"},"modified":"2021-07-29T10:42:01","modified_gmt":"2021-07-29T10:42:01","slug":"la-incomprendida-calculadora-de-harvard","status":"publish","type":"page","link":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/","title":{"rendered":"La incomprendida calculadora de Harvard"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"31679\" class=\"elementor elementor-31679 elementor-26896\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8dca3f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"b8dca3f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d293a21\" data-id=\"d293a21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0e899c elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"b0e899c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ac2869a\" data-id=\"ac2869a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-066da23 elementor-widget elementor-widget-menu-anchor\" data-id=\"066da23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"news\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a455852 elementor-widget elementor-widget-spacer\" data-id=\"a455852\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a4c0fa elementor-widget elementor-widget-text-editor\" data-id=\"7a4c0fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>NOTICIA\u2022 23.10.2020<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afe4b9a elementor-widget elementor-widget-text-editor\" data-id=\"afe4b9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 40px;\">La incomprendida calculadora de Harvard<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4d18ee elementor-widget elementor-widget-image\" data-id=\"a4d18ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"189\" height=\"9\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/11\/line-leaf-single-right.svg\" class=\"attachment-medium_large size-medium_large wp-image-31456\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57ff06b elementor-widget elementor-widget-text-editor\" data-id=\"57ff06b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><strong>En agosto de este a\u00f1o, la <a href=\"https:\/\/schools.forhealth.org\/\" target=\"_blank\" rel=\"noopener\">Foundation \u201cSchools for Health\u201d <\/a>para la mejora de la salud de ni\u00f1os y j\u00f3venes en el \u00e1mbito del colegio public\u00f3 una gu\u00eda que nos indicaba c\u00f3mo saber si la tasa de ventilaci\u00f3n de las aulas era la adecuada para el correcto comienzo del curso escolar ante la situaci\u00f3n actual de la pandemia del COVID-19. El estudio nos indica un m\u00e9todo para determinar la capacidad de renovaci\u00f3n del aire de los sistemas de ventilaci\u00f3n en las escuelas y si el caudal movido por estos era suficiente o no.<\/strong><\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df5924d elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"df5924d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-334136c\" data-id=\"334136c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b0bcf4 elementor-widget elementor-widget-spacer\" data-id=\"4b0bcf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8004c6b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"8004c6b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f739c5e\" data-id=\"f739c5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f4c38 elementor-widget elementor-widget-spacer\" data-id=\"62f4c38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef77e1d elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"ef77e1d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20dfac9\" data-id=\"20dfac9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de1494 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"1de1494\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-04164f0\" data-id=\"04164f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-751151b elementor-widget elementor-widget-text-editor\" data-id=\"751151b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 20px;\">Dimensiones de las aulas<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3db6b99 elementor-widget elementor-widget-text-editor\" data-id=\"3db6b99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\"><\/div>\n<p class=\"NormalINA\">El impecable tratamiento t\u00e9cnico de la gu\u00eda preve\u00eda la posibilidad de no poder ventilar correctamente y abr\u00eda la puerta, mucho m\u00e1s que correcta y aconsejable, de suplir esta carencia con sistemas de purificaci\u00f3n de aire basados en filtro HEPA. El caudal no aportado por aire exterior se compensaba por ese mismo caudal de aire purificado. Para ello nos enlazaba con una calculadora de selecci\u00f3n de equipos basada en las caracter\u00edsticas t\u00e9cnicas de los mismos.<\/p>\n<p class=\"NormalINA\"><span lang=\"EN-GB\"><a href=\"https:\/\/tinyurl.com\/portableaircleanertool\" target=\"-blank\">Este enlace<\/a> , nos lleva a una hoja de Excel donde con solo introducir las dimensiones del aula nos daba la caracter\u00edstica del purificador necesario. Esta caracter\u00edstica se basaba en el CADR (caudal de aire filtrado) que deb\u00eda de cumplir el equipo.<\/span><\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-947a10a elementor-widget elementor-widget-image\" data-id=\"947a10a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"803\" height=\"345\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot.png\" class=\"attachment-large size-large wp-image-46557\" alt=\"\" srcset=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot.png 803w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-300x129.png 300w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-768x330.png 768w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-800x345.png 800w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-700x301.png 700w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a675eb5 elementor-widget elementor-widget-text-editor\" data-id=\"a675eb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"row wpb_row vc_inner row-fluid\">\n<div class=\"wpb_column columns small-12 medium-4 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p class=\"NormalINA\"><span lang=\"EN-GB\">The fact of only considering the volume of the room leaving aside the occupation is not in accordance with the Spanish regulations, but that it was based on ASHRAE 62.1 standards led me to investigate this, at first glance, a contradiction. <\/span>Indeed, the calculations were exact, their application correct, but not applicable to the reality we face in Spanish schools.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-518fbdb elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"518fbdb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-152e2ba\" data-id=\"152e2ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc46cf1 elementor-widget elementor-widget-spacer\" data-id=\"cc46cf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8cd2aa elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"b8cd2aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4517340\" data-id=\"4517340\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-166c194 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"166c194\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3887d7b\" data-id=\"3887d7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15c32b9 elementor-widget elementor-widget-text-editor\" data-id=\"15c32b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 20px;\">M\u00e9todo ASHRAE<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b86ce2e elementor-widget elementor-widget-text-editor\" data-id=\"b86ce2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"row wpb_row row-fluid\">\n<div class=\"wpb_column columns small-12 medium-12 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"row wpb_row vc_inner row-fluid\">\n<div class=\"wpb_column columns small-12 medium-6 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p class=\"NormalINA\">Si analizamos como se aplican los c\u00e1lculos debemos ir a la hoja \u201cREADME\u201d, donde explica con detalle los datos tenidos en cuenta para ello. Lo que nos encontramos en ella es que el m\u00e9todo ASHRAE para ventilaci\u00f3n es aplicado como:<\/p>\n<ul>\n<li class=\"NormalINA\">5 l\/s persona<\/li>\n<li class=\"NormalINA\">6 l\/s m\u00b2<\/li>\n<\/ul>\n<div class=\"row wpb_row row-fluid\">\n<div class=\"wpb_column columns small-12 medium-12 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p class=\"NormalINA\">Este planteamiento ser\u00eda correcto bajo est\u00e1ndares ASHRAE pero estar\u00eda fuera de Norma para Espa\u00f1a, por:<\/p>\n<\/div>\n<\/div>\n<div class=\"row wpb_row vc_inner row-fluid\">\n<div class=\"wpb_column columns small-12 medium-6 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<ul>\n<li class=\"NormalINA\">RITE enfoca la ventilaci\u00f3n a las personas, no a las superficies<\/li>\n<li class=\"NormalINA\">RITE ventila personas, no superficies. Los caudales RITE son dos, escuelas y aulas en general 45 m\u00b3\/h persona y guarder\u00edas 72 m\u00b3\/h persona.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column columns small-12 medium-6 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row wpb_row row-fluid\">\n<div class=\"wpb_column columns small-12 medium-12 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p class=\"NormalINA\">La verdad es que este aspecto se podr\u00eda obviar si el resultado final fuera pr\u00e1ctico, pero no lo es. El par\u00e1metro fundamental del c\u00e1lculo se basa en el aforo, mejor dicho, densidad de aforo, que la calculadora tomaba como base de c\u00e1lculo. Este valor era de 25 personas en una sala de 1.000 pies\u00b2 (92 m\u00b2), impensables en Espa\u00f1a donde en 40 m\u00b2 acoplamos c\u00f3modamente a esas 25 personas.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af57547 elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"af57547\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4079863\" data-id=\"4079863\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a68dbc elementor-widget elementor-widget-spacer\" data-id=\"0a68dbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7316c39 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"7316c39\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e022824\" data-id=\"e022824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfcc209 elementor-widget elementor-widget-spacer\" data-id=\"dfcc209\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e8366e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"5e8366e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a6f730\" data-id=\"2a6f730\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fbabf71 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"fbabf71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-694f5d7\" data-id=\"694f5d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abc8607 elementor-widget elementor-widget-text-editor\" data-id=\"abc8607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 20px;\">Uso incorrecto de la calculadora<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d601b82 elementor-widget elementor-widget-text-editor\" data-id=\"d601b82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p class=\"NormalINA\">El mal uso de esta calculadora lleva a errores de subdimensionado del 70% al 100% para colegios y de un 112% a un 150% para guarder\u00edas, nada desde\u00f1able, pero sobre todo al error de sentirse seguro por haberlo hecho bien bajo est\u00e1ndares mucho m\u00e1s que avalados.<\/p>\n<p class=\"NormalINA\">El hecho es que para un aula de 50m\u00b2 nos indica como buena, con \u201cventilaci\u00f3n natural t\u00edpica\u201d de 1.5 renovaciones\/hora y con una ocupaci\u00f3n de 13 personas, un aporte purificado de 3.1 renovaciones\/hora.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65c8543 elementor-widget elementor-widget-image\" data-id=\"65c8543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"803\" height=\"345\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot.png\" class=\"attachment-large size-large wp-image-46557\" alt=\"\" srcset=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot.png 803w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-300x129.png 300w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-768x330.png 768w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-800x345.png 800w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/02\/harvard-calc-screenshot-700x301.png 700w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c83a9e3 elementor-widget elementor-widget-text-editor\" data-id=\"c83a9e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>TPara nuestras ocupaciones, 25 personas en 50m\u00b2, las tasas de nuestra ventilaci\u00f3n indican entre 7-8 renovaciones\/hora, bien dicho, 1.125 m\u00b3\/h filtrado mediante prefiltro F6 y filtro F8, a los que si restamos esa \u201cventilaci\u00f3n natural\u201d de 1.5 renovaci\u00f3n\/hora, m\u00e1s que dudosa, nos indica una tasa de aire purificado de 6.5 renovaciones\/hora. Dato muy alejado de lo obtenido por la Calculadora.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-512045d elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"512045d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dd04a2\" data-id=\"0dd04a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac2397e elementor-widget elementor-widget-spacer\" data-id=\"ac2397e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c06f306 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"c06f306\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9cbcc6c\" data-id=\"9cbcc6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ca52a52 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"ca52a52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8d14e1b\" data-id=\"8d14e1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8d2a95 elementor-widget elementor-widget-text-editor\" data-id=\"e8d2a95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 20px;\">Conclusi\u00f3n<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c4b843 elementor-widget elementor-widget-text-editor\" data-id=\"7c4b843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"row wpb_row row-fluid\">\n<div class=\"wpb_column columns small-12 medium-12 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"row wpb_row vc_inner row-fluid\">\n<div class=\"wpb_column columns small-12 medium-6 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Como se indic\u00f3 anteriormente este error se multiplica en guarder\u00edas. Como resumen final debemos indicar que:<\/p>\n<ul>\n<li>Si bien, la calculadora es correct\u00edsima bajo Norma ASHARAE, su aplicaci\u00f3n directa en Espa\u00f1a es inviable y peligrosa.<\/li>\n<li>Calcular caudales de renovaci\u00f3n de aire sin conocer el aforo es muy arriesgado.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cfb876 elementor-widget elementor-widget-text-editor\" data-id=\"8cfb876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 20px;\">La Soluci\u00f3n<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3008860 elementor-widget elementor-widget-text-editor\" data-id=\"3008860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"row wpb_row row-fluid\">\n<div class=\"wpb_column columns small-12 medium-12 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"row wpb_row vc_inner row-fluid\">\n<div class=\"wpb_column columns small-12 medium-6 thb-dark-column\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Con los estudios llevados a cabo por los equipos de I+D+i de KEYTER se ha desarrollado <a href=\"http:\/\/xj45abc.keyter.com\/airsanit-solutions\/\">AirSanit<\/a>, Unidad de Tratamiento de Aire y Purificaci\u00f3n de KEYTER que ya ha obtenido la Certificaci\u00f3n Anti-COVID del Instituto Nacional de T\u00e9cnicas Aeroespaciales de Espa\u00f1a. Desde KEYTER seguimos trabajando cada d\u00eda para poner al servicio de la lucha contra el COVID-19 toda nuestra experiencia y conocimiento.<\/p>\n<p>Este es s\u00f3lo un ejemplo de c\u00f3mo seguimos trabajando para poner toda nuestra experiencia y conocimientos al servicio de la lucha mundial contra el COVID-19.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f75d3b9 elementor-widget elementor-widget-spacer\" data-id=\"f75d3b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aea44b8 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"aea44b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3dd37f9\" data-id=\"3dd37f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f5dd11 elementor-widget elementor-widget-image\" data-id=\"1f5dd11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"1188\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/07\/Jose-Arboledas-Formacion-y-Proyectos-Especiales-KEYTER.png\" class=\"attachment-full size-full wp-image-39111\" alt=\"\" srcset=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/07\/Jose-Arboledas-Formacion-y-Proyectos-Especiales-KEYTER.png 1600w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/07\/Jose-Arboledas-Formacion-y-Proyectos-Especiales-KEYTER-300x223.png 300w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/07\/Jose-Arboledas-Formacion-y-Proyectos-Especiales-KEYTER-1024x760.png 1024w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/07\/Jose-Arboledas-Formacion-y-Proyectos-Especiales-KEYTER-768x570.png 768w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/07\/Jose-Arboledas-Formacion-y-Proyectos-Especiales-KEYTER-1536x1140.png 1536w, https:\/\/www.keyter.com\/wp-content\/uploads\/2021\/07\/Jose-Arboledas-Formacion-y-Proyectos-Especiales-KEYTER-700x520.png 700w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-466db0c\" data-id=\"466db0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce51af6 elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"ce51af6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27ec8ef elementor-widget elementor-widget-text-editor\" data-id=\"27ec8ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00abAirSanit es uno de los m\u00e9todos que las escuelas pueden utilizar para su lucha contra los virus, como el COVID-19\u00bb.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01136cc elementor-widget elementor-widget-image\" data-id=\"01136cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"189\" height=\"9\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/11\/line-leaf-single-right.svg\" class=\"attachment-thumbnail size-thumbnail wp-image-31456\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3822d8 elementor-widget elementor-widget-text-editor\" data-id=\"e3822d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jos\u00e9 Arboledas (Proyectos Especiales y Formaci\u00f3n)<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4904460 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"4904460\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a786c53\" data-id=\"a786c53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76f269b elementor-widget elementor-widget-heading\" data-id=\"76f269b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">M\u00e1s noticias<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-126feed elementor-widget elementor-widget-text-editor\" data-id=\"126feed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfTe interesan todas nuestras noticias, art\u00edculos y actualizaciones? L\u00e9elas todas y mantente al d\u00eda.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f7783d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8f7783d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/noticias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">NOTICIAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e00532 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"6e00532\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef54069\" data-id=\"ef54069\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d675e6a elementor-widget elementor-widget-text-editor\" data-id=\"d675e6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00c1S SOBRE KEYTER<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-728e2c9 elementor-widget elementor-widget-text-editor\" data-id=\"728e2c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 40px;\">\u00bfEn qu\u00e9 estas interesado?<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8962285 elementor-widget elementor-widget-image\" data-id=\"8962285\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"9\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/10\/line-leaf.svg\" class=\"attachment-medium size-medium wp-image-45826\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f2bd1a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"f2bd1a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c479597\" data-id=\"c479597\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9275094 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9275094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/nuestra-historia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">NUESTRA HISTORIA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1020588\" data-id=\"1020588\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fa913f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7fa913f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/productos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">GAMA DE PRODUCTOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-dc8c956\" data-id=\"dc8c956\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-036be14 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"036be14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/referencias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REFERENCIAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-40374d3\" data-id=\"40374d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1780b4a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1780b4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/empleo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">TRABAJA CON NOSOTROS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>NOTICIA\u2022 23.10.2020 La incomprendida calculadora de Harvard En agosto de este a\u00f1o, la Foundation \u201cSchools for Health\u201d para la mejora de la salud de ni\u00f1os y j\u00f3venes en el \u00e1mbito del colegio public\u00f3 una gu\u00eda que nos indicaba c\u00f3mo saber si la tasa de ventilaci\u00f3n&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-31679","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La incomprendida calculadora de Harvard - Keyter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La incomprendida calculadora de Harvard - Keyter\" \/>\n<meta property=\"og:description\" content=\"NOTICIA\u2022 23.10.2020 La incomprendida calculadora de Harvard En agosto de este a\u00f1o, la Foundation \u201cSchools for Health\u201d para la mejora de la salud de ni\u00f1os y j\u00f3venes en el \u00e1mbito del colegio public\u00f3 una gu\u00eda que nos indicaba c\u00f3mo saber si la tasa de ventilaci\u00f3n...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/\" \/>\n<meta property=\"og:site_name\" content=\"Keyter\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-29T10:42:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/11\/line-leaf-single-right.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/\",\"url\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/\",\"name\":\"La incomprendida calculadora de Harvard - Keyter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.keyter.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/line-leaf-single-right.svg\",\"datePublished\":\"2021-05-10T06:58:58+00:00\",\"dateModified\":\"2021-07-29T10:42:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.keyter.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/line-leaf-single-right.svg\",\"contentUrl\":\"https:\\\/\\\/www.keyter.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/line-leaf-single-right.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/la-incomprendida-calculadora-de-harvard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La incomprendida calculadora de Harvard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/\",\"name\":\"Keyter\",\"description\":\"Leading thermodynamic technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La incomprendida calculadora de Harvard - Keyter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/","og_locale":"es_ES","og_type":"article","og_title":"La incomprendida calculadora de Harvard - Keyter","og_description":"NOTICIA\u2022 23.10.2020 La incomprendida calculadora de Harvard En agosto de este a\u00f1o, la Foundation \u201cSchools for Health\u201d para la mejora de la salud de ni\u00f1os y j\u00f3venes en el \u00e1mbito del colegio public\u00f3 una gu\u00eda que nos indicaba c\u00f3mo saber si la tasa de ventilaci\u00f3n...","og_url":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/","og_site_name":"Keyter","article_modified_time":"2021-07-29T10:42:01+00:00","og_image":[{"url":"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/11\/line-leaf-single-right.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/","url":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/","name":"La incomprendida calculadora de Harvard - Keyter","isPartOf":{"@id":"https:\/\/www.keyter.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/#primaryimage"},"image":{"@id":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/#primaryimage"},"thumbnailUrl":"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/11\/line-leaf-single-right.svg","datePublished":"2021-05-10T06:58:58+00:00","dateModified":"2021-07-29T10:42:01+00:00","breadcrumb":{"@id":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/#primaryimage","url":"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/11\/line-leaf-single-right.svg","contentUrl":"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/11\/line-leaf-single-right.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.keyter.com\/es\/la-incomprendida-calculadora-de-harvard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.keyter.com\/es\/"},{"@type":"ListItem","position":2,"name":"La incomprendida calculadora de Harvard"}]},{"@type":"WebSite","@id":"https:\/\/www.keyter.com\/es\/#website","url":"https:\/\/www.keyter.com\/es\/","name":"Keyter","description":"Leading thermodynamic technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.keyter.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages\/31679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/comments?post=31679"}],"version-history":[{"count":8,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages\/31679\/revisions"}],"predecessor-version":[{"id":39124,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages\/31679\/revisions\/39124"}],"wp:attachment":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/media?parent=31679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}