{"id":69184,"date":"2023-12-22T08:29:49","date_gmt":"2023-12-22T08:29:49","guid":{"rendered":"https:\/\/www.keyter.com\/cierre-i-campana-unidos-por-un-juguete\/"},"modified":"2023-12-22T08:29:50","modified_gmt":"2023-12-22T08:29:50","slug":"cierre-i-campana-unidos-por-un-juguete","status":"publish","type":"page","link":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/","title":{"rendered":"Cierre I Campa\u00f1a \u00bbUnidos por un Juguete\u00bb"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"69184\" class=\"elementor elementor-69184 elementor-69160\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35fb782 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"35fb782\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-828a3ad\" data-id=\"828a3ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f8f03c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"f8f03c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3584d49\" data-id=\"3584d49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-792c507 e-grid-align-right elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"792c507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-a8c6510\" href=\"https:\/\/es.linkedin.com\/company\/keyter\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-3362250\" href=\"https:\/\/www.facebook.com\/keyterHVACR\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-3f1e49f\" href=\"https:\/\/twitter.com\/KEYTERes\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-2b5a944\" href=\"https:\/\/www.youtube.com\/channel\/UCMHOMneQyaueda5RocUOBog\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6eaf735 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"6eaf735\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f871be\" data-id=\"0f871be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-637bcc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"637bcc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-be064da\" data-id=\"be064da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57e52e4 elementor-widget elementor-widget-text-editor\" data-id=\"57e52e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>NOTICIAS \u2022 20.12.2023<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aa8b53 elementor-widget elementor-widget-text-editor\" data-id=\"9aa8b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 26px;\">Cierre I Campa\u00f1a \u00bbUnidos por un Juguete\u00bb<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3b73e7 elementor-widget elementor-widget-text-editor\" data-id=\"a3b73e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text );\"><strong>El Grupo KEYTER<\/strong>, conformado por las empresas <a href=\"https:\/\/www.keyter.com\/es\/\">KEYTER<\/a>, <a href=\"https:\/\/ww.intarcon.com\">INTARCON<\/a>, y <a href=\"https:\/\/ww.genaq.com\">GENAQ<\/a>, se enorgullece en anunciar el \u00e9xito de su primera campa\u00f1a solidaria, \u00ab<strong>Unidos por un Juguete<\/strong>\u00bb La iniciativa, destinada a la recogida de juguetes para la asociaci\u00f3n Lucena Acoge, ha superado todas las expectativas con la entrega de m\u00e1s de 300 juguetes por parte de los empleados de las tres compa\u00f1\u00edas.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8138551 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8138551\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8138551\" data-elementor-lightbox-title=\"1702989574068\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjkxNjcsInVybCI6Imh0dHBzOlwvXC93d3cua2V5dGVyLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTJcLzE3MDI5ODk1NzQwNjguanBnIiwic2xpZGVzaG93IjoiODEzODU1MSJ9\" href=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574068.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574068.jpg\" alt=\"1702989574068\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8138551\" data-elementor-lightbox-title=\"1702989574401\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjkxNzIsInVybCI6Imh0dHBzOlwvXC93d3cua2V5dGVyLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTJcLzE3MDI5ODk1NzQ0MDEuanBnIiwic2xpZGVzaG93IjoiODEzODU1MSJ9\" href=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574401.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574401.jpg\" alt=\"1702989574401\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8138551\" data-elementor-lightbox-title=\"KEYTER GROUP RECORTADA\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjkxNzcsInVybCI6Imh0dHBzOlwvXC93d3cua2V5dGVyLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTJcL0tFWVRFUi1HUk9VUC1SRUNPUlRBREEuanBnIiwic2xpZGVzaG93IjoiODEzODU1MSJ9\" href=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/KEYTER-GROUP-RECORTADA.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/KEYTER-GROUP-RECORTADA.jpg\" alt=\"KEYTER GROUP RECORTADA\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-becdbf4 elementor-widget elementor-widget-text-editor\" data-id=\"becdbf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La entrega de los juguetes tuvo lugar en un emotivo acto donde los representantes de Lucena Acoge expresaron su sorpresa y gratitud al ver la generosidad y solidaridad demostrada por los trabajadores de KEYTER, INTARCON y GENAQ. La cantidad de juguetes recolectados asegura que muchos ni\u00f1os disfrutar\u00e1n de una Navidad llena de ilusi\u00f3n y alegr\u00eda.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7dc20c elementor-widget elementor-widget-text-editor\" data-id=\"a7dc20c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La direcci\u00f3n del Grupo KEYTER desea expresar su m\u00e1s sincero agradecimiento a todos los empleados que participaron en la Campa\u00f1a \u00abUnidos por un Juguete\u00bb. Gracias a su colaboraci\u00f3n desinteresada, se ha logrado llevar alegr\u00eda a los ni\u00f1os de Lucena Acoge.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe458c elementor-widget elementor-widget-text-editor\" data-id=\"bfe458c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Campa\u00f1a \u00abUnidos por un Juguete\u00bb no solo representa el compromiso social del Grupo KEYTER, sino tambi\u00e9n el esp\u00edritu solidario y la empat\u00eda de sus empleados. El impacto positivo de esta iniciativa contribuir\u00e1 a crear un recuerdo inolvidable para muchos ni\u00f1os durante estas fechas especiales.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f00c505 elementor-widget elementor-widget-text-editor\" data-id=\"f00c505\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gracias por hacer posible la I Campa\u00f1a \u00ab\ud835\ude50\ud835\ude63\ud835\ude5e\ud835\ude59\ud835\ude64\ud835\ude68 \ud835\ude65\ud835\ude64\ud835\ude67 \ud835\ude6a\ud835\ude63 \ud835\ude5f\ud835\ude6a\ud835\ude5c\ud835\ude6a\ud835\ude5a\ud835\ude69\ud835\ude5a\u00bb \u26bd\ufe0f\ud83e\ude80\u26f8\ud83e\uddf8. <strong>El Grupo KEYTER<\/strong> espera que esta sea la primera de muchas iniciativas destinadas a mejorar la vida de quienes m\u00e1s lo necesitan.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0232de6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"0232de6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-911c817\" data-id=\"911c817\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e587b5c\" data-id=\"e587b5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74a61fd elementor-widget elementor-widget-spacer\" data-id=\"74a61fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7dec1d2\" data-id=\"7dec1d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9198cee elementor-widget elementor-widget-image\" data-id=\"9198cee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/keyter-intarcon.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/11\/KEYTER-GROUP-POSITIVO-RGB.png\" title=\"KEYTER GROUP POSITIVO RGB\" alt=\"KEYTER GROUP POSITIVO RGB\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0b503ed\" data-id=\"0b503ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7210db0 elementor-widget elementor-widget-spacer\" data-id=\"7210db0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-279a272\" data-id=\"279a272\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0972e7 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"e0972e7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9900aa6\" data-id=\"9900aa6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c21fa5 elementor-widget elementor-widget-spacer\" data-id=\"4c21fa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6d3e95 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"e6d3e95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5735e8\" data-id=\"e5735e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51fa38a elementor-widget elementor-widget-heading\" data-id=\"51fa38a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">M\u00e1s noticias<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c75f5b elementor-widget elementor-widget-text-editor\" data-id=\"6c75f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfLe interesan todas nuestras noticias, art\u00edculos y actualizaciones? L\u00e9alos todos y mant\u00e9ngase al d\u00eda.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d10584 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1d10584\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/noticias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">NOTICIAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cfb5775 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"cfb5775\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fec5411\" data-id=\"fec5411\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0d933e elementor-widget elementor-widget-text-editor\" data-id=\"c0d933e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00c1S SOBRE KEYTER<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c4d122 elementor-widget elementor-widget-text-editor\" data-id=\"2c4d122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-size: 40px;\">\u00bfC\u00f3mo podemos ayudarte?<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b01f76b elementor-widget elementor-widget-image\" data-id=\"b01f76b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"369\" height=\"9\" src=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2020\/10\/line-leaf.svg\" class=\"attachment-medium size-medium wp-image-45826\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c68b7cb elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"c68b7cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6cf4743\" data-id=\"6cf4743\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-309be93 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"309be93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/nuestra-historia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">NUESTRA HISTORIA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e563b17\" data-id=\"e563b17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdead2d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bdead2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/productos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PRODUCTOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a04405f\" data-id=\"a04405f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40e6c4b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"40e6c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/referencias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REFERENCIAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cd597c5\" data-id=\"cd597c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eddf82c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"eddf82c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.keyter.com\/es\/empleo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">TRABAJA CON NOSOTROS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Linkedin Facebook Twitter Youtube NOTICIAS \u2022 20.12.2023 Cierre I Campa\u00f1a \u00bbUnidos por un Juguete\u00bb El Grupo KEYTER, conformado por las empresas KEYTER, INTARCON, y GENAQ, se enorgullece en anunciar el \u00e9xito de su primera campa\u00f1a solidaria, \u00abUnidos por un Juguete\u00bb La iniciativa, destinada a la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-69184","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cierre I Campa\u00f1a &#039;&#039;Unidos por un Juguete&#039;&#039; - Keyter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cierre I Campa\u00f1a &#039;&#039;Unidos por un Juguete&#039;&#039; - Keyter\" \/>\n<meta property=\"og:description\" content=\"Linkedin Facebook Twitter Youtube NOTICIAS \u2022 20.12.2023 Cierre I Campa\u00f1a \u00bbUnidos por un Juguete\u00bb El Grupo KEYTER, conformado por las empresas KEYTER, INTARCON, y GENAQ, se enorgullece en anunciar el \u00e9xito de su primera campa\u00f1a solidaria, \u00abUnidos por un Juguete\u00bb La iniciativa, destinada a la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/\" \/>\n<meta property=\"og:site_name\" content=\"Keyter\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-22T08:29:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574068.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/\",\"url\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/\",\"name\":\"Cierre I Campa\u00f1a ''Unidos por un Juguete'' - Keyter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.keyter.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/1702989574068.jpg\",\"datePublished\":\"2023-12-22T08:29:49+00:00\",\"dateModified\":\"2023-12-22T08:29:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.keyter.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/1702989574068.jpg\",\"contentUrl\":\"https:\\\/\\\/www.keyter.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/1702989574068.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/cierre-i-campana-unidos-por-un-juguete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cierre I Campa\u00f1a &#8221;Unidos por un Juguete&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/\",\"name\":\"Keyter\",\"description\":\"Leading thermodynamic technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.keyter.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cierre I Campa\u00f1a ''Unidos por un Juguete'' - Keyter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/","og_locale":"es_ES","og_type":"article","og_title":"Cierre I Campa\u00f1a ''Unidos por un Juguete'' - Keyter","og_description":"Linkedin Facebook Twitter Youtube NOTICIAS \u2022 20.12.2023 Cierre I Campa\u00f1a \u00bbUnidos por un Juguete\u00bb El Grupo KEYTER, conformado por las empresas KEYTER, INTARCON, y GENAQ, se enorgullece en anunciar el \u00e9xito de su primera campa\u00f1a solidaria, \u00abUnidos por un Juguete\u00bb La iniciativa, destinada a la...","og_url":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/","og_site_name":"Keyter","article_modified_time":"2023-12-22T08:29:50+00:00","og_image":[{"url":"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574068.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/","url":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/","name":"Cierre I Campa\u00f1a ''Unidos por un Juguete'' - Keyter","isPartOf":{"@id":"https:\/\/www.keyter.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/#primaryimage"},"image":{"@id":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574068.jpg","datePublished":"2023-12-22T08:29:49+00:00","dateModified":"2023-12-22T08:29:50+00:00","breadcrumb":{"@id":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/#primaryimage","url":"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574068.jpg","contentUrl":"https:\/\/www.keyter.com\/wp-content\/uploads\/2023\/12\/1702989574068.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.keyter.com\/es\/cierre-i-campana-unidos-por-un-juguete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.keyter.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cierre I Campa\u00f1a &#8221;Unidos por un Juguete&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.keyter.com\/es\/#website","url":"https:\/\/www.keyter.com\/es\/","name":"Keyter","description":"Leading thermodynamic technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.keyter.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages\/69184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/comments?post=69184"}],"version-history":[{"count":1,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages\/69184\/revisions"}],"predecessor-version":[{"id":69185,"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/pages\/69184\/revisions\/69185"}],"wp:attachment":[{"href":"https:\/\/www.keyter.com\/es\/wp-json\/wp\/v2\/media?parent=69184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}